{"id":861,"count":1,"description":"","link":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/location\/az-85013\/","name":"AZ 85013","slug":"az-85013","taxonomy":"location","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.1 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>AZ 85013 Archives - Net Solutions Interactive<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AZ 85013 Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.netsolutionscorp.com\/senior-care-services\/location\/az-85013\/\" \/>\n<meta property=\"og:site_name\" content=\"Net Solutions Interactive\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/location\\\/az-85013\\\/\",\"url\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/location\\\/az-85013\\\/\",\"name\":\"AZ 85013 Archives - Net Solutions Interactive\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/location\\\/az-85013\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/location\\\/az-85013\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AZ 85013\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/#website\",\"url\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/\",\"name\":\"Net Solutions Interactive\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/#organization\",\"name\":\"Net Solutions Interactive\",\"url\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/main_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/main_logo-1.png\",\"width\":588,\"height\":225,\"caption\":\"Net Solutions Interactive\"},\"image\":{\"@id\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"AZ 85013 Archives - Net Solutions Interactive","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"AZ 85013 Archives","og_url":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/location\/az-85013\/","og_site_name":"Net Solutions Interactive","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/location\/az-85013\/","url":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/location\/az-85013\/","name":"AZ 85013 Archives - Net Solutions Interactive","isPartOf":{"@id":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/#website"},"breadcrumb":{"@id":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/location\/az-85013\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/location\/az-85013\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/"},{"@type":"ListItem","position":2,"name":"AZ 85013"}]},{"@type":"WebSite","@id":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/#website","url":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/","name":"Net Solutions Interactive","description":"","publisher":{"@id":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/#organization","name":"Net Solutions Interactive","url":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/#\/schema\/logo\/image\/","url":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/wp-content\/uploads\/2019\/05\/main_logo-1.png","contentUrl":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/wp-content\/uploads\/2019\/05\/main_logo-1.png","width":588,"height":225,"caption":"Net Solutions Interactive"},"image":{"@id":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/wp-json\/wp\/v2\/location\/861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/wp-json\/wp\/v2\/location"}],"about":[{"href":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/wp-json\/wp\/v2\/taxonomies\/location"}],"wp:post_type":[{"href":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/wp-json\/wp\/v2\/listing?location=861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}