{"id":195,"date":"2019-10-03T11:53:59","date_gmt":"2019-10-03T11:53:59","guid":{"rendered":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/?post_type=listing&#038;p=195"},"modified":"2020-05-11T00:08:49","modified_gmt":"2020-05-11T00:08:49","slug":"hospice-in-byron-ca","status":"publish","type":"listing","link":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/near-me\/hospice-in-byron-ca\/","title":{"rendered":"hospice in byron ca &#8211; Golden State Home Health Care"},"content":{"rendered":"","protected":false},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","listing-category":[4],"list-tags":[],"location":[98],"class_list":["post-195","listing","type-listing","status-publish","hentry","listing-category-hospices","location-ca-95376"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.1 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>hospice in byron ca - Golden State Home Health Care - Net Solutions Interactive<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.netsolutionscorp.com\/senior-care-services\/near-me\/hospice-in-byron-ca\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"hospice in byron ca - Golden State Home Health Care\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.netsolutionscorp.com\/senior-care-services\/near-me\/hospice-in-byron-ca\/\" \/>\n<meta property=\"og:site_name\" content=\"Net Solutions Interactive\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-11T00:08:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/near-me\\\/hospice-in-byron-ca\\\/\",\"url\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/near-me\\\/hospice-in-byron-ca\\\/\",\"name\":\"hospice in byron ca - Golden State Home Health Care - Net Solutions Interactive\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/#website\"},\"datePublished\":\"2019-10-03T11:53:59+00:00\",\"dateModified\":\"2020-05-11T00:08:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/near-me\\\/hospice-in-byron-ca\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/near-me\\\/hospice-in-byron-ca\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/near-me\\\/hospice-in-byron-ca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"hospice in byron ca &#8211; Golden State Home Health Care\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/#website\",\"url\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/\",\"name\":\"Net Solutions Interactive\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/#organization\",\"name\":\"Net Solutions Interactive\",\"url\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/main_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/main_logo-1.png\",\"width\":588,\"height\":225,\"caption\":\"Net Solutions Interactive\"},\"image\":{\"@id\":\"https:\\\/\\\/www.netsolutionscorp.com\\\/senior-care-services\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"hospice in byron ca - Golden State Home Health Care - Net Solutions Interactive","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/near-me\/hospice-in-byron-ca\/","og_locale":"en_US","og_type":"article","og_title":"hospice in byron ca - Golden State Home Health Care","og_url":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/near-me\/hospice-in-byron-ca\/","og_site_name":"Net Solutions Interactive","article_modified_time":"2020-05-11T00:08:49+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/near-me\/hospice-in-byron-ca\/","url":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/near-me\/hospice-in-byron-ca\/","name":"hospice in byron ca - Golden State Home Health Care - Net Solutions Interactive","isPartOf":{"@id":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/#website"},"datePublished":"2019-10-03T11:53:59+00:00","dateModified":"2020-05-11T00:08:49+00:00","breadcrumb":{"@id":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/near-me\/hospice-in-byron-ca\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.netsolutionscorp.com\/senior-care-services\/near-me\/hospice-in-byron-ca\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/near-me\/hospice-in-byron-ca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/"},{"@type":"ListItem","position":2,"name":"hospice in byron ca &#8211; Golden State Home Health Care"}]},{"@type":"WebSite","@id":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/#website","url":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/","name":"Net Solutions Interactive","description":"","publisher":{"@id":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/#organization","name":"Net Solutions Interactive","url":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/#\/schema\/logo\/image\/","url":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/wp-content\/uploads\/2019\/05\/main_logo-1.png","contentUrl":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/wp-content\/uploads\/2019\/05\/main_logo-1.png","width":588,"height":225,"caption":"Net Solutions Interactive"},"image":{"@id":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/wp-json\/wp\/v2\/listing\/195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/wp-json\/wp\/v2\/listing"}],"about":[{"href":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/wp-json\/wp\/v2\/types\/listing"}],"author":[{"embeddable":true,"href":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/wp-json\/wp\/v2\/comments?post=195"}],"wp:attachment":[{"href":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/wp-json\/wp\/v2\/media?parent=195"}],"wp:term":[{"taxonomy":"listing-category","embeddable":true,"href":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/wp-json\/wp\/v2\/listing-category?post=195"},{"taxonomy":"list-tags","embeddable":true,"href":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/wp-json\/wp\/v2\/list-tags?post=195"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/www.netsolutionscorp.com\/senior-care-services\/wp-json\/wp\/v2\/location?post=195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}